{"id":6615,"date":"2020-12-03T21:18:28","date_gmt":"2020-12-03T19:18:28","guid":{"rendered":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico.jpg"},"modified":"2020-12-03T21:18:28","modified_gmt":"2020-12-03T19:18:28","slug":"pandoro-classico","status":"inherit","type":"attachment","link":"https:\/\/www.sologusto.com\/lt\/pandoro-classico\/","title":{"rendered":"pandoro-classico"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-6615","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/aenU2I-1IH","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"187\" src=\"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-300x187.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-300x187.jpg 300w, https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-768x480.jpg 768w, https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-160x100.jpg 160w, https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-600x375.jpg 600w, https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico.jpg 810w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"6615\" data-permalink=\"https:\/\/www.sologusto.com\/lt\/pandoro-classico\/\" data-orig-file=\"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico.jpg\" data-orig-size=\"810,506\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"pandoro-classico\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico.jpg\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":810,"height":506,"file":"2020\/12\/pandoro-classico.jpg","sizes":{"medium":{"file":"pandoro-classico-300x187.jpg","width":300,"height":187,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-300x187.jpg"},"thumbnail":{"file":"pandoro-classico-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-150x150.jpg"},"medium_large":{"file":"pandoro-classico-768x480.jpg","width":768,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-768x480.jpg"},"post-thumbnail":{"file":"pandoro-classico-765x380.jpg","width":765,"height":380,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-765x380.jpg"},"canape-testimonial-thumbnail":{"file":"pandoro-classico-90x90.jpg","width":90,"height":90,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-90x90.jpg"},"canape-logo":{"file":"pandoro-classico-160x100.jpg","width":160,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-160x100.jpg"},"woocommerce_thumbnail":{"file":"pandoro-classico-300x300.jpg","width":300,"height":300,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-300x300.jpg"},"woocommerce_single":{"file":"pandoro-classico-600x375.jpg","width":600,"height":375,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-600x375.jpg"},"woocommerce_gallery_thumbnail":{"file":"pandoro-classico-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-100x100.jpg"},"shop_catalog":{"file":"pandoro-classico-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-300x300.jpg"},"shop_single":{"file":"pandoro-classico-600x375.jpg","width":600,"height":375,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-600x375.jpg"},"shop_thumbnail":{"file":"pandoro-classico-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico-100x100.jpg"},"full":{"file":"pandoro-classico.jpg","width":810,"height":506,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/12\/pandoro-classico.jpg","_links":{"self":[{"href":"https:\/\/www.sologusto.com\/lt\/wp-json\/wp\/v2\/media\/6615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sologusto.com\/lt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.sologusto.com\/lt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.sologusto.com\/lt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sologusto.com\/lt\/wp-json\/wp\/v2\/comments?post=6615"}]}}