{"id":5394,"date":"2020-02-22T10:47:23","date_gmt":"2020-02-22T08:47:23","guid":{"rendered":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio.png"},"modified":"2020-02-22T10:48:24","modified_gmt":"2020-02-22T08:48:24","slug":"colombapistacchio","status":"inherit","type":"attachment","link":"https:\/\/www.sologusto.com\/lt\/colombapistacchio\/","title":{"rendered":"colombapistacchio"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-5394","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/aenU2I-1p0","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"296\" src=\"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio-300x296.png\" class=\"attachment-medium size-medium\" alt=\"Colomba pistacchio\" srcset=\"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio-300x296.png 300w, https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio-100x100.png 100w, https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio-600x593.png 600w, https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio.png 676w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"5394\" data-permalink=\"https:\/\/www.sologusto.com\/lt\/colombapistacchio\/\" data-orig-file=\"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio.png\" data-orig-size=\"676,668\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"colombapistacchio\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio.png\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Colomba pistacchio","media_type":"image","mime_type":"image\/png","media_details":{"width":676,"height":668,"file":"2020\/02\/colombapistacchio.png","sizes":{"woocommerce_thumbnail":{"file":"colombapistacchio-300x300.png","width":300,"height":300,"uncropped":false,"mime_type":"image\/png","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio-300x300.png"},"woocommerce_gallery_thumbnail":{"file":"colombapistacchio-100x100.png","width":100,"height":100,"mime_type":"image\/png","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio-100x100.png"},"woocommerce_single":{"file":"colombapistacchio-600x593.png","width":600,"height":593,"mime_type":"image\/png","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio-600x593.png"},"medium":{"file":"colombapistacchio-300x296.png","width":300,"height":296,"mime_type":"image\/png","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio-300x296.png"},"thumbnail":{"file":"colombapistacchio-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio-150x150.png"},"twentyseventeen-thumbnail-avatar":{"file":"colombapistacchio-100x100.png","width":100,"height":100,"mime_type":"image\/png","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio-100x100.png"},"shop_catalog":{"file":"colombapistacchio-300x300.png","width":300,"height":300,"uncropped":false,"mime_type":"image\/png","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio-300x300.png"},"shop_single":{"file":"colombapistacchio-600x593.png","width":600,"height":593,"mime_type":"image\/png","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio-600x593.png"},"shop_thumbnail":{"file":"colombapistacchio-100x100.png","width":100,"height":100,"mime_type":"image\/png","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio-100x100.png"},"woocommerce_thumbnail_preview":{"file":"colombapistacchio-324x324.png","width":324,"height":324,"mime_type":"image\/png","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio-324x324.png"},"full":{"file":"colombapistacchio.png","width":676,"height":668,"mime_type":"image\/png","source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.sologusto.com\/wp-content\/uploads\/2020\/02\/colombapistacchio.png","_links":{"self":[{"href":"https:\/\/www.sologusto.com\/lt\/wp-json\/wp\/v2\/media\/5394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sologusto.com\/lt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.sologusto.com\/lt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.sologusto.com\/lt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sologusto.com\/lt\/wp-json\/wp\/v2\/comments?post=5394"}]}}